{"id":2819,"date":"2020-02-09T11:35:44","date_gmt":"2020-02-09T10:35:44","guid":{"rendered":"http:\/\/www.edit.si\/izdelki\/pet-kunststoffband\/"},"modified":"2020-03-26T11:02:10","modified_gmt":"2020-03-26T10:02:10","slug":"pet-kunststoffband","status":"publish","type":"izdelki","link":"https:\/\/www.edit.si\/de\/pet-kunststoffband","title":{"rendered":"PET-Kunststoffband"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2819\" class=\"elementor elementor-2819 elementor-1701\" data-elementor-post-type=\"izdelki\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6614b5c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6614b5c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b5d4ba3\" data-id=\"b5d4ba3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-371757c elementor-widget elementor-widget-image\" data-id=\"371757c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.edit.si\/wp-content\/uploads\/2020\/02\/povezovalni_trakovi_PET_plasticni_02.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"povezovalni trakovi PET plasticni 02\" data-elementor-lightbox-description=\"povezovalni trakovi PET plasticni 02\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxMCwidXJsIjoiaHR0cHM6XC9cL3d3dy5lZGl0LnNpXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIwXC8wMlwvcG92ZXpvdmFsbmlfdHJha292aV9QRVRfcGxhc3RpY25pXzAyLmpwZyJ9\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.edit.si\/wp-content\/uploads\/elementor\/thumbs\/povezovalni_trakovi_PET_plasticni_02-ref98deuvzw1fxx0pnxgjfiziuptzu35pym7kbumiw.jpg\" title=\"povezovalni trakovi PET plasticni 02\" alt=\"povezovalni trakovi PET plasticni 02\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e39690c elementor-widget elementor-widget-jet-listing-dynamic-field\" data-id=\"e39690c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;img_slider_cols&quot;:&quot;3&quot;,&quot;img_slider_cols_tablet&quot;:&quot;2&quot;,&quot;img_slider_cols_mobile&quot;:&quot;2&quot;}\" data-widget_type=\"jet-listing-dynamic-field.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"jet-listing jet-listing-dynamic-field display-multiline\"><div class=\"jet-listing-dynamic-field__content\" ><div class=\"jet-engine-gallery-slider swiper-lib\" data-atts=\"{&quot;slidesToShow&quot;:3,&quot;dots&quot;:false,&quot;slidesToScroll&quot;:1,&quot;adaptiveHeight&quot;:true,&quot;autoHeight&quot;:true,&quot;prevArrow&quot;:&quot;&lt;div class=&#039;prev-arrow jet-engine-arrow slick-arrow&#039;&gt;&lt;svg width=&#039;180&#039; height=&#039;180&#039; viewBox=&#039;0 0 180 180&#039; fill=&#039;yes&#039; xmlns=&#039;http:\\\/\\\/www.w3.org\\\/2000\\\/svg&#039;&gt;&lt;path d=&#039;M119 47.3166C119 48.185 118.668 48.9532 118.003 49.6212L78.8385 89L118.003 128.379C118.668 129.047 119 129.815 119 130.683C119 131.552 118.668 132.32 118.003 132.988L113.021 137.998C112.356 138.666 111.592 139 110.729 139C109.865 139 109.101 138.666 108.436 137.998L61.9966 91.3046C61.3322 90.6366 61 89.8684 61 89C61 88.1316 61.3322 87.3634 61.9966 86.6954L108.436 40.002C109.101 39.334 109.865 39 110.729 39C111.592 39 112.356 39.334 113.021 40.002L118.003 45.012C118.668 45.68 119 46.4482 119 47.3166Z&#039; fill=&#039;black&#039;\\\/&gt;&lt;\\\/svg&gt;&lt;\\\/div&gt;&quot;,&quot;nextArrow&quot;:&quot;&lt;div class=&#039;next-arrow jet-engine-arrow slick-arrow&#039;&gt;&lt;svg width=&#039;180&#039; height=&#039;180&#039; viewBox=&#039;0 0 180 180&#039; fill=&#039;yes&#039; xmlns=&#039;http:\\\/\\\/www.w3.org\\\/2000\\\/svg&#039;&gt;&lt;path d=&#039;M61 48.3166C61 49.185 61.3322 49.9532 61.9966 50.6212L101.162 90L61.9966 129.379C61.3322 130.047 61 130.815 61 131.683C61 132.552 61.3322 133.32 61.9966 133.988L66.9794 138.998C67.6438 139.666 68.4078 140 69.2715 140C70.1352 140 70.8992 139.666 71.5636 138.998L118.003 92.3046C118.668 91.6366 119 90.8684 119 90C119 89.1316 118.668 88.3634 118.003 87.6954L71.5636 41.002C70.8992 40.334 70.1352 40 69.2715 40C68.4078 40 67.6438 40.334 66.9794 41.002L61.9966 46.012C61.3322 46.68 61 47.4482 61 48.3166Z&#039; fill=&#039;black&#039;\\\/&gt;&lt;\\\/svg&gt;&lt;\\\/div&gt;&quot;,&quot;rtl&quot;:false,&quot;responsive&quot;:[{&quot;breakpoint&quot;:1025,&quot;settings&quot;:{&quot;slidesToShow&quot;:2}},{&quot;breakpoint&quot;:768,&quot;settings&quot;:{&quot;slidesToShow&quot;:2}}]}\"><div class=\"swiper-wrapper\"><div class=\"jet-engine-gallery-slider__item\"><a href=\"https:\/\/www.edit.si\/wp-content\/uploads\/2020\/02\/povezovalni_trakovi_PET_plasticni_01.jpg\" class=\"jet-engine-gallery-slider__item-wrap jet-engine-gallery-item-wrap is-lightbox\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"gallery_9490\" data-elementor-lightbox-title=\"povezovalni trakovi PET plasticni 01\" data-elementor-lightbox-description=\"povezovalni trakovi PET plasticni 01\"><div class=\"jet-engine-lightbox-icon is-svg-icon\"><svg class=\"e-font-icon-svg e-fas-plus-circle\" aria-hidden=\"true\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zm144 276c0 6.6-5.4 12-12 12h-92v92c0 6.6-5.4 12-12 12h-56c-6.6 0-12-5.4-12-12v-92h-92c-6.6 0-12-5.4-12-12v-56c0-6.6 5.4-12 12-12h92v-92c0-6.6 5.4-12 12-12h56c6.6 0 12 5.4 12 12v92h92c6.6 0 12 5.4 12 12v56z\"><\/path><\/svg><\/div><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.edit.si\/wp-content\/uploads\/2020\/02\/povezovalni_trakovi_PET_plasticni_01-150x150.jpg\" class=\"jet-engine-gallery-slider__item-img item-image-fullwidth\" alt=\"povezovalni trakovi PET plasticni 01\" \/><\/a><\/div><div class=\"jet-engine-gallery-slider__item\"><a href=\"https:\/\/www.edit.si\/wp-content\/uploads\/2020\/02\/povezovalni_trakovi_PP_plasticni_04_odvijalec.jpg\" class=\"jet-engine-gallery-slider__item-wrap jet-engine-gallery-item-wrap is-lightbox\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"gallery_9490\" data-elementor-lightbox-title=\"povezovalni trakovi PP plasticni 04 odvijalec\" data-elementor-lightbox-description=\"povezovalni trakovi PP plasticni 04 odvijalec\"><div class=\"jet-engine-lightbox-icon is-svg-icon\"><svg class=\"e-font-icon-svg e-fas-plus-circle\" aria-hidden=\"true\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zm144 276c0 6.6-5.4 12-12 12h-92v92c0 6.6-5.4 12-12 12h-56c-6.6 0-12-5.4-12-12v-92h-92c-6.6 0-12-5.4-12-12v-56c0-6.6 5.4-12 12-12h92v-92c0-6.6 5.4-12 12-12h56c6.6 0 12 5.4 12 12v92h92c6.6 0 12 5.4 12 12v56z\"><\/path><\/svg><\/div><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.edit.si\/wp-content\/uploads\/2020\/02\/povezovalni_trakovi_PP_plasticni_04_odvijalec-150x150.jpg\" class=\"jet-engine-gallery-slider__item-img item-image-fullwidth\" alt=\"povezovalni trakovi PP plasticni 04 odvijalec\" srcset=\"https:\/\/www.edit.si\/wp-content\/uploads\/2020\/02\/povezovalni_trakovi_PP_plasticni_04_odvijalec-150x150.jpg 150w, https:\/\/www.edit.si\/wp-content\/uploads\/2020\/02\/povezovalni_trakovi_PP_plasticni_04_odvijalec-300x300.jpg 300w, https:\/\/www.edit.si\/wp-content\/uploads\/2020\/02\/povezovalni_trakovi_PP_plasticni_04_odvijalec.jpg 500w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><\/div><div class=\"jet-engine-gallery-slider__item\"><a href=\"https:\/\/www.edit.si\/wp-content\/uploads\/2020\/02\/povezovalni_trakovi_plasticni_vogalnik.jpg\" class=\"jet-engine-gallery-slider__item-wrap jet-engine-gallery-item-wrap is-lightbox\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"gallery_9490\" data-elementor-lightbox-title=\"povezovalni trakovi plasticni vogalnik\" data-elementor-lightbox-description=\"povezovalni trakovi plasticni vogalnik\"><div class=\"jet-engine-lightbox-icon is-svg-icon\"><svg class=\"e-font-icon-svg e-fas-plus-circle\" aria-hidden=\"true\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zm144 276c0 6.6-5.4 12-12 12h-92v92c0 6.6-5.4 12-12 12h-56c-6.6 0-12-5.4-12-12v-92h-92c-6.6 0-12-5.4-12-12v-56c0-6.6 5.4-12 12-12h92v-92c0-6.6 5.4-12 12-12h56c6.6 0 12 5.4 12 12v92h92c6.6 0 12 5.4 12 12v56z\"><\/path><\/svg><\/div><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.edit.si\/wp-content\/uploads\/2020\/02\/povezovalni_trakovi_plasticni_vogalnik-150x150.jpg\" class=\"jet-engine-gallery-slider__item-img item-image-fullwidth\" alt=\"povezovalni trakovi plasticni vogalnik\" \/><\/a><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d383ae0\" data-id=\"d383ae0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2e6b1d3 elementor-widget elementor-widget-text-editor\" data-id=\"2e6b1d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>PET Umreifungsb\u00e4nder (auch Superb\u00e4nder genannt) zeichnen sich durch eine gro\u00dfe Zugfestigkeit aus und werden deshalb als Alternative zum Stahlumreifungsband verwendet. Sie sind st\u00e4rker als PP-Umreifungsb\u00e4nder und sind deshalb f\u00fcr das Umreifen der mittelschweren Ware oder Paletten geeignet. Sie \u00fcbertragen ausgezeichnet pl\u00f6tzliche Temperatur\u00e4nderungen und wegen kleinerer Ausdehnung (im Vergleich zu PP-B\u00e4ndern), garantieren sie eine konstante Spannung der umreiften Fracht w\u00e4hrend der Lagermanipulation.<\/p>\n<h2>Anwendung<\/h2>\n<p>Das Band kann zusammen mit Hand- oder Batterieheftern oder auf halb- und vollautomatischen Umreifungsmaschinen verwendet werden. Bei Handheftern werden zur Bandfixierung Klemmen verwendet. Im Gegensatz zu den Klemmen machen halbautomatische oder Batteriemaschinen eine Schwei\u00dfnaht, was als bessere L\u00f6sung betrachtet wird. Zur leichteren Verwendung und zum Transport von B\u00e4ndern werden Bandabroller verwendet. Zum Kantenschutz werden Plastikeckensch\u00fctzer benutzt.<\/p>\n<h2>Abmessungen und Eigenschaften der B\u00e4nder<\/h2>\n<table class=\"table table-striped table-hover\" border=\"0\" cellspacing=\"1\" cellpadding=\"1\">\n<tbody>\n<tr>\n<th scope=\"col\">Breite:<\/th>\n<td>9, 12, 16, 19, 32 mm<\/td>\n<\/tr>\n<tr>\n<th scope=\"col\">St\u00e4rke:<\/th>\n<td>von 0,50 bis 1,30 mm<\/td>\n<\/tr>\n<tr>\n<th scope=\"col\">Zugfestigkeit:<\/th>\n<td>ist eine sehr bedeutende Eigenschaft des Bandes. Sie sagt aus, wie stark ein Band maximal belastbar ist. Die Zugfestigkeit wird durch Breite und St\u00e4rke definiert.<\/td>\n<\/tr>\n<tr>\n<th scope=\"col\">Der innere Rollendurchmesser:<\/th>\n<td>406 mm<\/td>\n<\/tr>\n<tr>\n<th scope=\"col\">Dehnung :<\/th>\n<td>10 \u2013 15%<\/td>\n<\/tr>\n<tr>\n<th scope=\"col\">Standardfarbe:<\/th>\n<td>gr\u00fcn<\/td>\n<\/tr>\n<tr>\n<th scope=\"col\">Druck:<\/th>\n<td>m\u00f6glich ist 3-farbiger Druck auf dem Band, der einen sichereren Transport Ihrer Ware garantiert. Er kann auch zu Informations- und Werbezwecken verwendet werden, wodurch Sie das Renommee Ihres Unternehmens verbessern k\u00f6nnen.<\/td>\n<\/tr>\n<tr>\n<th scope=\"col\">UV-Best\u00e4ndigkeit:<\/th>\n<td>hoch<\/td>\n<\/tr>\n<tr>\n<th scope=\"col\">Arbeitstemperatur:<\/th>\n<td>von -18 bis +75\u00b0C<\/td>\n<\/tr>\n<tr>\n<th scope=\"col\">Recyclebarkeit:<\/th>\n<td>100%<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<div>F\u00fcr leichtere Manipulation empfehlen wir Ihnen den Abrollwagen mit praktischem Ablagekasten, der ein gleichm\u00e4\u00dfiges Abrollen des Bandes erm\u00f6glicht. Er ist geeignet f\u00fcr innere Rollendurchmesser 200, 280 und 406 mm.<\/div>\n<div>\n<p>Bei Verwendung von Umreifungsb\u00e4ndern werden oft Plastikeckensch\u00fctzer benutzt, deren Aufgabe ist es, die Bandkraft auf eine gr\u00f6\u00dfere Fl\u00e4che zu verteilen. Damit werden eventuelle durch Bandr\u00e4nder verursachende Sch\u00e4den an der Ware verhindert.<\/p>\n<div>\n<p>Ausf\u00fchrungen:<\/p>\n<ul>\n<li>30mm \u2013 Kartoninhalt 2000 St\u00fcck<\/li>\n<li>50mm \u2013 Kartoninhalt 500 St\u00fcck<\/li>\n<\/ul>\n<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d68a1e1 elementor-widget elementor-widget-text-editor\" data-id=\"d68a1e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>PET-B\u00e4nder stellen eine\u00a0<strong>Alternative zum Stahlband<\/strong>\u00a0dar. Im Vergleich zu ihm haben sie folgende Vorteile:<\/p>\n<ul>\n<li>Der Preis pro Meter ist im Vergleich zum Stahlband um ca. 40 Prozent niedriger.<\/li>\n<li>Sie rosten nicht.<\/li>\n<li>Die Handhabung ist sicherer.<\/li>\n<li>ehr hohe Zugfestigkeit weniger besch\u00e4digte Produkte<\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"featured_media":0,"template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"podrocje":[215],"class_list":["post-2819","izdelki","type-izdelki","status-publish","hentry","podrocje-umreifungsbander"],"_links":{"self":[{"href":"https:\/\/www.edit.si\/de\/wp-json\/wp\/v2\/izdelki\/2819","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.edit.si\/de\/wp-json\/wp\/v2\/izdelki"}],"about":[{"href":"https:\/\/www.edit.si\/de\/wp-json\/wp\/v2\/types\/izdelki"}],"version-history":[{"count":0,"href":"https:\/\/www.edit.si\/de\/wp-json\/wp\/v2\/izdelki\/2819\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.edit.si\/de\/wp-json\/wp\/v2\/media?parent=2819"}],"wp:term":[{"taxonomy":"podrocje","embeddable":true,"href":"https:\/\/www.edit.si\/de\/wp-json\/wp\/v2\/podrocje?post=2819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}